{"id":4814,"date":"2025-11-29T15:24:01","date_gmt":"2025-11-29T14:24:01","guid":{"rendered":"https:\/\/strohsterne-dietz.de\/?post_type=product&#038;p=4814"},"modified":"2026-01-10T18:59:05","modified_gmt":"2026-01-10T17:59:05","slug":"silhouetten-schere","status":"publish","type":"product","link":"https:\/\/strohsterne-dietz.de\/en\/product\/silhouetten-schere\/","title":{"rendered":"Silhouetten-Schere"},"content":{"rendered":"<p>Silhouettenscheren eignen sich besonders zum Schneiden von einzelnen Halmen und zum Trimmen filigraner Strohsterne. Ebenso f\u00fcr pr\u00e4zises Schneiden von Strohintarsien, Papier, Karton,Wellpappe, Filz und Stoffe.<\/p>\n<p>Weniger geeignet f\u00fcr Pfeifenputzer und Chenilledraht. Hierzu bitte kr\u00e4ftige Bastelschere oder Seitenschneider (Schmuckbastelwerkzeug) verwenden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Silhouetten-Scheren-Set f\u00fcr feine Schnitte bis an die Spitze. F\u00fcr alle feinere Stroharbeiten.<\/p>\n","protected":false},"featured_media":4815,"comment_status":"open","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/strohsterne-dietz.de\/en\/wp-json\/wp\/v2\/product\/4814"}],"collection":[{"href":"https:\/\/strohsterne-dietz.de\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/strohsterne-dietz.de\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/strohsterne-dietz.de\/en\/wp-json\/wp\/v2\/comments?post=4814"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strohsterne-dietz.de\/en\/wp-json\/wp\/v2\/media\/4815"}],"wp:attachment":[{"href":"https:\/\/strohsterne-dietz.de\/en\/wp-json\/wp\/v2\/media?parent=4814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}