{"id":291,"date":"2019-09-11T22:43:34","date_gmt":"2019-09-11T20:43:34","guid":{"rendered":"https:\/\/project.benjaminhanke.de\/strohsterne-dietz\/produkt\/import-placeholder-for-532\/"},"modified":"2025-10-27T12:00:42","modified_gmt":"2025-10-27T11:00:42","slug":"klebeetikett-din-a4-unbedruckt","status":"publish","type":"product","link":"https:\/\/strohsterne-dietz.de\/en\/product\/klebeetikett-din-a4-unbedruckt\/","title":{"rendered":"Klebeetikett DIN A4 (unbedruckt)"},"content":{"rendered":"<p>F\u00fcr eigene Strohbilder, ohne Dekoration (Karten, Stroh etc.)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>F\u00fcr eigene Strohbilder, ohne Dekoration (Karten, Stroh etc.)<\/p>\n","protected":false},"featured_media":82,"comment_status":"open","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/strohsterne-dietz.de\/en\/wp-json\/wp\/v2\/product\/291"}],"collection":[{"href":"https:\/\/strohsterne-dietz.de\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/strohsterne-dietz.de\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/strohsterne-dietz.de\/en\/wp-json\/wp\/v2\/comments?post=291"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strohsterne-dietz.de\/en\/wp-json\/wp\/v2\/media\/82"}],"wp:attachment":[{"href":"https:\/\/strohsterne-dietz.de\/en\/wp-json\/wp\/v2\/media?parent=291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}