{"id":280,"date":"2019-09-11T22:43:32","date_gmt":"2019-09-11T20:43:32","guid":{"rendered":"https:\/\/project.benjaminhanke.de\/strohsterne-dietz\/produkt\/import-placeholder-for-521\/"},"modified":"2026-04-17T10:14:57","modified_gmt":"2026-04-17T08:14:57","slug":"strohspalter-4-fach","status":"publish","type":"product","link":"https:\/\/strohsterne-dietz.de\/en\/product\/strohspalter-4-fach\/","title":{"rendered":"Strohspalter 4-fach"},"content":{"rendered":"<p>Kein Einweichen und B\u00fcgeln mehr wie fr\u00fcher! Die Halme werden einfach durch den Spalter geschoben, wobei gleich breite Halmstreifen entstehen. Diese werden gek\u00fcrzt und in die jeweilige Legeform eingelegt. Dicke Halme ergeben nat\u00fcrlich breitere Teile als d\u00fcnne Halme. So bestimmt man , ob man eher filigrane oder rustikalere Sterne machen m\u00f6chte. Mit dem 4er Spalter erh\u00e4lt man nat\u00fcrlich ohnehin breitere Teile als mit dem 6er Spalter.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hilfsmittel zum gefahrlosen Spalten der Strohhalme. Spaltet das Stroh in 4 gleich breite Streifen.<\/p>\n","protected":false},"featured_media":138,"comment_status":"open","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/strohsterne-dietz.de\/en\/wp-json\/wp\/v2\/product\/280"}],"collection":[{"href":"https:\/\/strohsterne-dietz.de\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/strohsterne-dietz.de\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/strohsterne-dietz.de\/en\/wp-json\/wp\/v2\/comments?post=280"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strohsterne-dietz.de\/en\/wp-json\/wp\/v2\/media\/138"}],"wp:attachment":[{"href":"https:\/\/strohsterne-dietz.de\/en\/wp-json\/wp\/v2\/media?parent=280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}