{"id":270,"date":"2019-09-11T22:43:32","date_gmt":"2019-09-11T20:43:32","guid":{"rendered":"https:\/\/project.benjaminhanke.de\/strohsterne-dietz\/produkt\/import-placeholder-for-511\/"},"modified":"2025-01-13T08:54:05","modified_gmt":"2025-01-13T07:54:05","slug":"strohkugeln-6cm-sortiment-9-stueck","status":"publish","type":"product","link":"https:\/\/strohsterne-dietz.de\/en\/product\/strohkugeln-6cm-sortiment-9-stueck\/","title":{"rendered":"Strohkugeln, 6cm, Sortiment, 9 St\u00fcck"},"content":{"rendered":"<p>Christbaumschmuck aus Naturstroh zur Erg\u00e4nzung Ihrer selbst gemachten Strohsterne. Perfekt gearbeitete Strohkugeln, natur, 6 cm Durchmesser mit d\u00fcnnem Goldfaden zum Aufh\u00e4ngen.<\/p>\n<p><strong>Bastelidee<\/strong>: Mit Schleifchen versehen und auf die sonstige Deko farblich abstimmen. Aufh\u00e4nger zwischen die abgebundenen Halme ziehen, damit die Kugel sch\u00f6n senkrecht h\u00e4ngt. Oder in einen gr\u00f6\u00dferen Strohring h\u00e4ngen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>9 perfekt gearbeitete Strohkugeln, natur, 6 cm Durchmesser, d\u00fcnner Goldfaden zum Aufh\u00e4ngen.<\/p>\n","protected":false},"featured_media":118,"comment_status":"open","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/strohsterne-dietz.de\/en\/wp-json\/wp\/v2\/product\/270"}],"collection":[{"href":"https:\/\/strohsterne-dietz.de\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/strohsterne-dietz.de\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/strohsterne-dietz.de\/en\/wp-json\/wp\/v2\/comments?post=270"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strohsterne-dietz.de\/en\/wp-json\/wp\/v2\/media\/118"}],"wp:attachment":[{"href":"https:\/\/strohsterne-dietz.de\/en\/wp-json\/wp\/v2\/media?parent=270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}