{"id":265,"date":"2019-09-11T22:43:32","date_gmt":"2019-09-11T20:43:32","guid":{"rendered":"https:\/\/project.benjaminhanke.de\/strohsterne-dietz\/produkt\/import-placeholder-for-506\/"},"modified":"2026-03-22T05:25:53","modified_gmt":"2026-03-22T04:25:53","slug":"strohsterne-wie-schneekristalle-anleitungsheft-2-32-s-s-w","status":"publish","type":"product","link":"https:\/\/strohsterne-dietz.de\/en\/product\/strohsterne-wie-schneekristalle-anleitungsheft-2-32-s-s-w\/","title":{"rendered":"neu: Strohsterne wie Schneekristalle Heft 2 &#8211; Neuauflage 2025, 36 S., f\u00fcr Universallegeform"},"content":{"rendered":"<p>Neuauflage 2025: Endlich ist es uns gelungen das Anleitungsheft 2 neu aufzulegen. Es beschreibt die wichtigsten Verwendungsm\u00f6glichkeiten der 10cm gro\u00dfen Universal-Legeform: 12er und 24er Sterne, einfach und kompliziert, filigran und rustikal. Auch wie man Sterne aus den kleineren Legeformen erweitert.<\/p>\n<p>Au\u00dferdem enth\u00e4lt es eine Anleitung zum Wickeln mit einer Sticknadel und viele Tipps zum Basteln.<\/p>\n<p>Solange der Vorrat reicht , legen wir immer eine Vorg\u00e4ngerversion des Heftes bei. Sie erhalten somit 2 Anleitungshefte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neuauflage 2025: Endlich ist es uns gelungen das Anleitungsheft 2 neu aufzulegen. Es beschreibt die wichtigsten Verwendungsm\u00f6glichkeiten der 10cm gro\u00dfen Universal-Legeform: 12er und 24er Sterne, einfach und kompliziert, filigran und rustikal. Auch wie man Sterne aus den kleineren Legeformen erweitert.<\/p>\n<p>Au\u00dferdem enth\u00e4lt es eine Anleitung zum Wickeln mit einer Sticknadel und viele Tipps zum Basteln.<\/p>\n<p>Solange der Vorrat reicht , legen wir immer eine Vorg\u00e4ngerversion des Heftes bei. Sie erhalten somit 2 Anleitungshefte.<\/p>\n","protected":false},"featured_media":4422,"comment_status":"open","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/strohsterne-dietz.de\/en\/wp-json\/wp\/v2\/product\/265"}],"collection":[{"href":"https:\/\/strohsterne-dietz.de\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/strohsterne-dietz.de\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/strohsterne-dietz.de\/en\/wp-json\/wp\/v2\/comments?post=265"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strohsterne-dietz.de\/en\/wp-json\/wp\/v2\/media\/4422"}],"wp:attachment":[{"href":"https:\/\/strohsterne-dietz.de\/en\/wp-json\/wp\/v2\/media?parent=265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}